{"id":197,"date":"2018-07-05T05:04:12","date_gmt":"2018-07-05T03:04:12","guid":{"rendered":"https:\/\/www.sagitta.at\/?p=197"},"modified":"2021-04-11T05:26:32","modified_gmt":"2021-04-11T03:26:32","slug":"rangiroa-in-den-tuamotus-juli-2018","status":"publish","type":"post","link":"https:\/\/www.sagitta.at\/index.php\/2018\/07\/05\/rangiroa-in-den-tuamotus-juli-2018\/","title":{"rendered":"Rangiroa &#8211; Tuamotus"},"content":{"rendered":"\n<h2 class=\"has-medium-font-size wp-block-heading\">Rangiroa, bei den Polynesiern auch Ra&#8217;iroa (weiter Himmel) genannt,<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">ist das gr\u00f6\u00dfte Atoll des Tuamotus Archipels, das zweitgr\u00f6\u00dfte Atoll unserer<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">Erde nach Kwajalein. 44 Seemeilen lang und 18 Seemeilen breit, 244<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">Seemeilen von Tautira im Nordosten Tahiti &#8211; Itis entfernt. 1600 km\u00b2, gesamte<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">Land\ufb02\u00e4che etwa 78 km\u00b2 auf 240 Motus aufgeteilt. 2300 Einwohner. Im<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">Nordwesten durch 2 P\u00e4sse auch f\u00fcr Yachten und Versorgungsschi\ufb00e<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">erreichbar.<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">Air Tahiti bietet t\u00e4glich eine Flugverbindung von und nach Tahiti.<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">Superm\u00e4rkte in den beiden Orten Avatoru und Tiputa erm\u00f6glichen uns, als<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">auch den Einheimischen, eine brauchbare Versorgung,zumindest besser als<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">in den anderen von uns besuchten Atollen, inklusive Fakarava.<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">Wir sind nach 3 Tagen im Juni 2018 am Ankerplatz vor Tautira auf<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">Tahiti Iti, wo auch James Cook seine Anker fallen lie\u00df (im wahrsten des<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">Wortes, einer davon ist vor dem Museum in Tahiti ausgestellt), mit Kurs NO<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">bei S\u00fcdostwind nach Rangiroa aufgebrochen. Das Jahr zuvor waren wir<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">bereits schon mal dort, auch dieses Jahr feiern wir Lambrinis Geburtstag in<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">Rangiroa.<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">18 bis 22 Knoten S\u00fcdostwind erm\u00f6glichte uns ein schnelles<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">Vorankommen mit Raumschotkurs, aber eine schr\u00e4g achterlich einfallende<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">Welle, teilweise bis zu 4 Meter hoch, sorgte f\u00fcr ein eher ungem\u00fctliches<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">Bordleben.<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">Othello war wieder in Hochform und gab sein bestes.Er schlief die<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">meiste Zeit im Salon!<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">Da wir nicht in der Nacht den Pass von Avatoru einlaufen wollten, &#8222;<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">bremsten&#8220; wir uns ab der Ostseite Rangiroas ein und k\u00e4mpften uns<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">morgens durch den Pass, bei noch auslaufenden Wasser. War interessant<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">mit teilweise unter 1 Knoten den Pass zu durchschleichen. So hatten wir<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">mehr von der Landschaft \ud83d\ude42 Beim n\u00e4chsten Mal w\u00fcrde ich WX Tide mehr<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">vertrauen als den Tides Guestimator. Der Unterschied f\u00fcr Stillwasser betrug<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">2 Stunden zwischen diesen gebr\u00e4uchlichen Tidenvoraussagen.<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">Unseren Ankerplatz fanden wir dann 5 NM weiter \u00f6stlich zwischen 13<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">anderen Yachten, bei Tiputa. 14 58.1763 S und 147 38.1965 W. Etwas rollig<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">bei SO Wind, aber f\u00fcr uns ertr\u00e4glich.<\/h2>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\">Tiputa Pass<\/p>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">Allerdings erwarten wir 2 Tage sp\u00e4ter Lambrinis Mutter aus<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">Dortmund. Ihr k\u00f6nnen wir nicht diese Schaukelei zumuten, aber der<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">Wetterbericht verspricht Ho\ufb00nung.<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">Am Ankunftstag ist die Welle so klein, dass wir sogar mit dem Dinghy<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">zum Flughafen fahren k\u00f6nnen um sie in Empfang zu nehmen.<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">Es gibt am Dock westlich des Tiputa Passes die M\u00f6glichkeit das Dinghy<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">am Kai fest zu machen. Daneben gleich zwei kleine Restaurants, Chez Lili<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">und Puna, die f\u00fcr uns das bessere Essen dieses Jahr hatte.<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">Beide bieten auch gratis WiFi mit Code an. Maximal etwa 30 KB\/s<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">download.<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">Die Preise f\u00fcr Hauptgerichte liegen bei rund 1600 XPF oder 13 \u20ac. 1<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">Flasche Hinano 500 ml f\u00fcr 600 XPF. Wenn man die Stra\u00dfe weiter hinaus<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">zum Pass geht, kommt man nach 200 Metern an den beiden Superm\u00e4rkten<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">vorbei. Am besten man nimmt auch ein paar Leckerlies f\u00fcr die vielen<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">freundlichen Stra\u00dfenhunde mit. Freundlich zu Menschen, aber wenn man<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">einen eigenen Hund hat, ist es besser diesen an Bord zu lassen. Die haben<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">ihre Reviere fest im Gri\ufb00. Letztes Jahr wurde ein Seglerhund von einer<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">Meute gejagt, dass er vor lauter Panik sogar \u00fcber die Kaimauer ins Meer<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">sprang. Wenn man dann weitergeht bis zum Tiputa Pass, kann man die<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">Bottle Nose Delphine in den Wellen spielen sehen. In diesem Pass k\u00f6nnen<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">bis zu 8 Knoten Strom laufen, das w\u00e4re dann wirklich schlechtes<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">Timing.<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">Letztes Jahr waren wir auch bei der blauen Lagune im Westen vor<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">Anker, 15 05.6228 S und 147 55.2284 W, und man\u00f6vrierten mit dem Dinghi<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">durch das Ri\ufb00 in Lagune. Das alleine war schon grenzwertig. Der<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">Ankerplatz ist rollig, die 20 Seemeilen von Tiputa aus lohnen sich unsere<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">Meinung nach nicht. Besser ist es eine Tour mitzumachen, dabei gibt es<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">auch Lunch auf einem Motu in der Lagune. Oder man l\u00e4sst es ganz<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">bleiben.<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">Diese Jahr wollen wir den \u00f6stliche Teil erkunden. Zuerst ging es einmal<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">18 Seemeilen nach S\u00fcden, zum Motu Faama, 15 14.0124 S und 147 42.4256<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">W, dort auf 10 Meter Sandgrund \ufb01el unser B\u00fcgelanker. Mit dem Dinghi<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">erkundeten wir die vulkanischen Felsformationen am Au\u00dfenri\ufb00. Es \ufb01nden<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">sich immer wieder neue Fotomotive rund um diese unwirklichen Felsen. 6<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">NM weiter passieren wir das im Palmenwald versteckte Kia Ora Sauvage<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">Hotel. Ein paar Meilen weiter entdecken wir dann einen Sendemasten. Vini<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">Empfang, aber keine M\u00f6glichkeit E-Mails zu laden. Die Bandbreite bewegte<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">sich zwischen 20 Bytes und 3 KB. Warum der hier steht, wo es kein Dorf<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">gibt, erschlie\u00dft sich uns nicht. Das Hotel alleine kann es wohl nicht sein, da<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">es auch nicht gerade nebenan liegt.<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">N\u00e4chster Ankerplatz 15 18.3423 S und 147 26.7164 W, n\u00f6rdlich des<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">Motu Terereamanu. Gut gesch\u00fctzt gegen den vorherrschenden Ostwind,<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">auch bei 18 Knoten kaum Welle durch ein \u00f6stlich gelegenes Flach. Mit dem<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">Dinghi fuhren wir die 1,3 NM retour um das alte, verlassene Dorf mit Kirche<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">und Friedhof zu erkunden. Die Kirche erinnert mit Ihrem Standort<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">zwischen den Palmen und nur 200 Meter vom Strand entfernt, an die erste<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">Kirche die Columbus im Film &#8222;Die Eroberung des Paradies&#8220;<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">erbaute.O\ufb00enbar \ufb01ndet sie heute keine Verwendung mehr und ist bereits<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">dem Verfall Preis gegeben. Der Friedhof ist schwer zu entdecken und<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">be\ufb01ndet sich in der N\u00e4he eines alten, verfallenen Steinhauses westlich der<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">Kirche.<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">In der N\u00e4he sind 3 kleine, nur zeitweise bewohnte H\u00e4uschen der<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">Einheimischen. Zisternen, Papaya im Garten, H\u00e4ngematte am Strand.<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">Einfach, aber schon vorstellbar f\u00fcr ein Wochenende. Auf dem R\u00fcckweg<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">kommt uns eine ausgewachsene Sau entgegen. Auf Grund Ihrer<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">beeindruckenden Dimension, ich sch\u00e4tzte sie mal so auf die 100 kg, lassen<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">wir ihr den Vortritt und begeben uns etwas abseits. Nach kurzem,<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">freundlichen Blickkontakt geht jeder dann seines Weges.<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">Wenn man mit dem Dinghi am Strand auf H\u00f6he des Ankerplatzes<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">anlandet, am besten bei Niedrigwasser, kann man das Ufer Richtung Westen<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">entlang wandern, etwa 1,2 km, dann kommt man zu einer wundersch\u00f6nen<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">Lagune, wo Sandb\u00e4nke bei Ebbe begehbar werden,dann kommt wieder eine<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">rauhe Felsenlandschaft direkt am Au\u00dfenri\ufb00, die genauso abweisend auf den<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">ersten Blick wirkt, wie die beim Motu Faama.Wenn mann n\u00e4her kommt,<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">entdeckt man kleine Lagunen zwischen den schro\ufb00en Felsen. Festes<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">Schuhwerk ist anzuraten, in unserem Fall erf\u00fcllten Crocs ihren Zweck.<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">Kleine Fischschw\u00e4rme warten in den bei Ebbe entstanden Teichen wieder<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">auf die Flut, Krabben ziehen ihre Spuren im Sand. Eine, zumindest zeitweise<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">paradiesische Landschaft.<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">Wir hatten \u00fcbrigens die 3 Tage die wir hier vor Anker lagen SO bis<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">Ostwind mit etwa 15 Knoten. Gesehen hatten wir kein einziges Boot. Weiter<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">ging es 9 Seemeilen Richtung Osten. Dort wollten wir wie im Bonnett Guide<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">angegeben einen Ankerplatz \ufb01nden. Viele Korallen, 22 Knoten Ostwind und<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">1 Meter Welle lie\u00dfen uns allerdings davon Abstand nehmen und nochmals 4<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">Seemeilen weiterzu dem \u00f6stlichsten Ankerplatz Rangiroas motoren.15<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">14.8357 S und 147 14.5288 W. Zwischen vielen Flachs \ufb01el unser Anker auf<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">knapp 10 Meter Sandboden. Genau rechtzeitig bevor eine Squall \u00fcber uns<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">dr\u00fcber zog, dank dieser wir 30 Liter Wasser sammeln konnten. Hier kann<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">man mehrere Tage verbringen und mit dem Dinghi die Umgebung<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">erkunden.<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">N\u00e4chster Stopp war das Motu Hauope, 4 NM westlich. 15 15.7641 S und<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">147 17.2821 W, Ankerplatz im Lee des Inselchens. Einige T\u00f6lpel,<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">Fregattev\u00f6gel und M\u00f6wen nutzen das St\u00fcck Land um zu nisten und<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">auszuruhen.<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">14 NM Nordwestlich be\ufb01ndet sich das Motu Nao Nao, das ein<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">Tauchrevier sein soll. Motu ist schon etwas weit hergeholt. 10 Meter Sand<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">mit einem Felsen und einem Strauch darauf. Auch hier wieder einige V\u00f6gel<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">die Ihre Kreise ziehen. Leider war das Wasser sehr tr\u00fcb, also segelten wir<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">mit Ostwind weiter zum Motu Mahito. Von dort wieder retour zu unserem<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">Ausgangspunkt beim Kia Ora Hotel. Alles in allem 75 Seemeilen innerhalb<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">der Lagune \u00f6stlich vom Tiputa Pass bei S\u00fcdost bis Ostwind von 12 bis 22<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">Knoten. Welle maximal 1 Meter.<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">Heute besuchten wir den Hauptort Avatoru, 9 km von Tiputa entfernt.<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">Da Auto stoppen nicht erfolgreich war, riefen wir uns ein Taxi, das uns f\u00fcr<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">1500 XPF fuhr. In einer kleinen Filiale der Bank de Tahiti konnte man \u20ac<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">wechseln. Es gibt mehrere kleine Superm\u00e4rkte, doch daf\u00fcr lohnt sich der<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">Weg nicht. Die beiden in Tiputa sind ausreichend und ohne Auto leicht zu<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">erreichen. Wasser kann man in der Mairie bekommen. 100 Liter kosten<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">1300 XPF. Man kauft eine Plastikkarte im B\u00fcro und kann damit dann<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">au\u00dferhalbs das Wasser entnehmen. Das kommt aber nicht in Frage f\u00fcr uns,<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">da mit dem Taxi 100 Liter Wasser auf 4300 XPF oder 36 \u20ac kommen<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">w\u00fcrden.Zur\u00fcck waren wir beim Auto stoppen erfolgreicher und lernten<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">wieder mal nette Leute kennen. Am Dock in Tiputa lag noch immer das<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">Versorgungsschi\ufb00 Dory, das schon um 3 Uhr nachts mit dem abladen<\/h2>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">begann.<\/h2>\n<div class=\"pvc_clear\"><\/div><p id=\"pvc_stats_197\" class=\"pvc_stats all  \" data-element-id=\"197\" style=\"\"><i class=\"pvc-stats-icon small\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/www.sagitta.at\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p><div class=\"pvc_clear\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Rangiroa, bei den Polynesiern auch Ra&#8217;iroa (weiter Himmel) genannt, ist das gr\u00f6\u00dfte Atoll des Tuamotus Archipels, das zweitgr\u00f6\u00dfte Atoll unserer Erde nach Kwajalein. 44 Seemeilen lang und 18 Seemeilen breit, 244 Seemeilen von Tautira im Nordosten Tahiti &#8211; Itis entfernt.<\/p>\n<p><a href=\"https:\/\/www.sagitta.at\/index.php\/2018\/07\/05\/rangiroa-in-den-tuamotus-juli-2018\/\" class=\"more-link\">Weiterlesen<span class=\"screen-reader-text\">Rangiroa &#8211; Tuamotus<\/span><\/a><\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_197\" class=\"pvc_stats all  \" data-element-id=\"197\" style=\"\"><i class=\"pvc-stats-icon small\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/www.sagitta.at\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"author":2,"featured_media":219,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-197","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-reiseberichte"],"a3_pvc":{"activated":true,"total_views":985,"today_views":0},"_links":{"self":[{"href":"https:\/\/www.sagitta.at\/index.php\/wp-json\/wp\/v2\/posts\/197","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sagitta.at\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sagitta.at\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sagitta.at\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sagitta.at\/index.php\/wp-json\/wp\/v2\/comments?post=197"}],"version-history":[{"count":6,"href":"https:\/\/www.sagitta.at\/index.php\/wp-json\/wp\/v2\/posts\/197\/revisions"}],"predecessor-version":[{"id":472,"href":"https:\/\/www.sagitta.at\/index.php\/wp-json\/wp\/v2\/posts\/197\/revisions\/472"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sagitta.at\/index.php\/wp-json\/wp\/v2\/media\/219"}],"wp:attachment":[{"href":"https:\/\/www.sagitta.at\/index.php\/wp-json\/wp\/v2\/media?parent=197"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sagitta.at\/index.php\/wp-json\/wp\/v2\/categories?post=197"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sagitta.at\/index.php\/wp-json\/wp\/v2\/tags?post=197"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}